{"id":7291,"date":"2017-06-15T23:35:49","date_gmt":"2017-06-15T23:35:49","guid":{"rendered":"http:\/\/todoapulmon-rafaela.com\/?p=7291"},"modified":"2017-06-15T23:35:49","modified_gmt":"2017-06-15T23:35:49","slug":"se-viene-el-regional-de-saltos-hipicos-3","status":"publish","type":"post","link":"https:\/\/todoapulmon-rafaela.com\/index.php\/2017\/06\/15\/se-viene-el-regional-de-saltos-hipicos-3\/","title":{"rendered":"Se viene el Regional de Saltos H\u00edpicos"},"content":{"rendered":"<p>Este fin de semana el Jockey Club de Rafaela ser\u00e1 escenario del tradicional torneo Regional de Saltos H\u00edpicos, donde se dar\u00e1n cita m\u00e1s de 100 binomios de distintos puntos de la regi\u00f3n y de otras provincias, como C\u00f3rdoba, Entre R\u00edos, Buenos Aires, entre otras.<\/p>\n<p>En la oportunidad se pondr\u00e1n en disputa la primera y segunda fecha del Clasificatorio para el Federal. Habr\u00e1 actividad en todas las categor\u00edas, resaltando que en Primera se espera un muy buen nivel de jinetes y amazonas.<\/p>\n<p>Este jueves en Todo a Pulm\u00f3n radio dialogamos con Jorgelina Valle, una de las representantes locales. Aqu\u00ed el audio:<\/p>\n<!--[if lt IE 9]><script>document.createElement('audio');<\/script><![endif]-->\n<audio class=\"wp-audio-shortcode\" id=\"audio-7291-1\" preload=\"none\" style=\"width: 100%;\" controls=\"controls\"><source type=\"audio\/mpeg\" src=\"http:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2017\/06\/15-6-17-SALTO-HIPICO.mp3?_=1\" \/><a href=\"http:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2017\/06\/15-6-17-SALTO-HIPICO.mp3\">http:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2017\/06\/15-6-17-SALTO-HIPICO.mp3<\/a><\/audio>\n","protected":false},"excerpt":{"rendered":"<p>Este fin de semana el Jockey Club de Rafaela ser\u00e1 escenario del tradicional torneo Regional de Saltos H\u00edpicos, donde se<\/p>\n","protected":false},"author":2,"featured_media":7286,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,15],"tags":[],"class_list":["post-7291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas","category-saltos-hipicos"],"cc_featured_image_caption":{"caption_text":"Se espera un muy buen nivel de protagonistas. La prueba principal ser\u00e1 a 1m35.","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/7291"}],"collection":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/comments?post=7291"}],"version-history":[{"count":1,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/7291\/revisions"}],"predecessor-version":[{"id":7292,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/7291\/revisions\/7292"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/media\/7286"}],"wp:attachment":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/media?parent=7291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/categories?post=7291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/tags?post=7291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}