{"id":58090,"date":"2025-07-07T19:23:44","date_gmt":"2025-07-07T19:23:44","guid":{"rendered":"https:\/\/todoapulmon-rafaela.com\/?p=58090"},"modified":"2025-07-07T19:23:44","modified_gmt":"2025-07-07T19:23:44","slug":"litoral-con-abril-beltramino-quinto-en-el-argentino","status":"publish","type":"post","link":"https:\/\/todoapulmon-rafaela.com\/index.php\/2025\/07\/07\/litoral-con-abril-beltramino-quinto-en-el-argentino\/","title":{"rendered":"Litoral, con Abril Beltramino, quinto en el Argentino"},"content":{"rendered":"<p>Se defini\u00f3 el Torneo Argentino de Selecciones \u00abGaby Pando\u00bb, que inici\u00f3 este mi\u00e9rcoles 2 de julio en la ciudad de Rosario, y termin\u00f3 el domingo 6 con la coronaci\u00f3n de Buenos Aires ante Mendoza.<\/p>\n<p>El seleccionado anfitri\u00f3n, Litoral, obtuvo el quinto puesto. En sus filas cont\u00f3 con la rafaelina Abril Beltramino, que convirti\u00f3 un gol en el torneo en la victoria ante San Juan por 3 a 2, el d\u00eda s\u00e1bado asegurando la permanencia en el nivel superior.<\/p>\n<p>En la fase clasificatoria, Litoral perdi\u00f3 1 a 0 con C\u00f3rdoba, empat\u00f3 2 a 2 con Salta y luego cay\u00f3 ante Mendoza 3 a 1.<\/p>\n<p>Luego de la victoria sobre San Juan, el domingo Litoral qued\u00f3 quinto al imponerse a Salta por 3 a 1.<\/p>\n<p>En el Torneo Campeonato Buenos Aires se hizo fuerte en los penales y se qued\u00f3 con el trofeo tras vencer a Mendoza. La batalla por el bronce qued\u00f3 en manos de la Federaci\u00f3n Cordobesa, que venci\u00f3 por 2 a 0 a Bah\u00eda Blanca y retuvo su lugar en el podio.<br \/>\nEn los partidos de Reubicaci\u00f3n A\/B, Tandil no pudo contrarrestar el poder\u00edo de San Juan y las damas del Valle de la Luna se impusieron 1 a 0 para ratificar su lugar en lo m\u00e1s alto del circuito de selecciones. A la inversa le ocurri\u00f3 a Tucum\u00e1n, Las Naranjas no lograron sobrepasar a su rival Mar del Plata y las de la Zona Balnearia de Buenos Aires se mantuvieron la m\u00e1xima divisi\u00f3n por propinarles un 2 a 1.<\/p>\n<p>En Caballeros fue campe\u00f3n Buenos Aires, segundo C\u00f3rdoba, tercero Mendoza, cuarto Litoral, quinto Tucum\u00e1n, sexto San Juan, s\u00e9ptimo Salta y octavo Santiago del Estero.<\/p>\n<p>Respecto a la Santafesina, tanto en damas como caballeros finalizaron en la duod\u00e9cima posici\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se defini\u00f3 el Torneo Argentino de Selecciones \u00abGaby Pando\u00bb, que inici\u00f3 este mi\u00e9rcoles 2 de julio en la ciudad de<\/p>\n","protected":false},"author":2,"featured_media":58092,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,24],"tags":[],"class_list":["post-58090","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hockey","category-noticias-destacadas"],"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/58090"}],"collection":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/comments?post=58090"}],"version-history":[{"count":2,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/58090\/revisions"}],"predecessor-version":[{"id":58093,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/58090\/revisions\/58093"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/media\/58092"}],"wp:attachment":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/media?parent=58090"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/categories?post=58090"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/tags?post=58090"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}