{"id":31225,"date":"2022-05-13T20:33:34","date_gmt":"2022-05-13T20:33:34","guid":{"rendered":"https:\/\/todoapulmon-rafaela.com\/?p=31225"},"modified":"2022-05-13T20:34:00","modified_gmt":"2022-05-13T20:34:00","slug":"la-lista-de-los-seleccionados-sub-16-de-la-fosh","status":"publish","type":"post","link":"https:\/\/todoapulmon-rafaela.com\/index.php\/2022\/05\/13\/la-lista-de-los-seleccionados-sub-16-de-la-fosh\/","title":{"rendered":"La lista de los seleccionados Sub 16 de la FOSH"},"content":{"rendered":"<p>La Federaci\u00f3n del Oeste Santafesino de Hockey sobre C\u00e9sped dio a conocer los seleccionados Sub 16, de las Zonas Rafaela y C\u00f3rdoba, que participar\u00e1n del torneo Regional a realizarse en Concordia, del 2 al 5 de junio.<\/p>\n<p>En el caso del representativo de la nuestra regi\u00f3n, del cual tenemos mayor conocimiento, hay varias jugadoras que ya tienen participaci\u00f3n en primera divisi\u00f3n. El entrenador ser\u00e1 Adri\u00e1n Kieffer (por motivos personales no podr\u00e1 trabajar Fabi\u00e1n Montesano con los seleccionados), teniendo cuatro jugadoras de CRAR, ocho de 9 de Julio, seis de Sarmiento de Humboldt, una de Bella Italia y una de Adelante de Reconquista.<\/p>\n<p>Estas son las seleccionadas:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-31226\" src=\"https:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2022\/05\/Placa-Rafaela-Sub-16.jpg\" alt=\"\" width=\"1440\" height=\"1440\" srcset=\"https:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2022\/05\/Placa-Rafaela-Sub-16.jpg 1440w, https:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2022\/05\/Placa-Rafaela-Sub-16-300x300.jpg 300w, https:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2022\/05\/Placa-Rafaela-Sub-16-150x150.jpg 150w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/p>\n<p>LISTA ZONA CORDOBA<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-31227\" src=\"https:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2022\/05\/Placa-Zona-Cordoba.jpg\" alt=\"\" width=\"1440\" height=\"1440\" srcset=\"https:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2022\/05\/Placa-Zona-Cordoba.jpg 1440w, https:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2022\/05\/Placa-Zona-Cordoba-300x300.jpg 300w, https:\/\/todoapulmon-rafaela.com\/wp-content\/uploads\/2022\/05\/Placa-Zona-Cordoba-150x150.jpg 150w\" sizes=\"(max-width: 1440px) 100vw, 1440px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Federaci\u00f3n del Oeste Santafesino de Hockey sobre C\u00e9sped dio a conocer los seleccionados Sub 16, de las Zonas Rafaela<\/p>\n","protected":false},"author":2,"featured_media":31228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,24],"tags":[],"class_list":["post-31225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-hockey","category-noticias-destacadas"],"cc_featured_image_caption":{"caption_text":"","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/31225"}],"collection":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/comments?post=31225"}],"version-history":[{"count":1,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/31225\/revisions"}],"predecessor-version":[{"id":31229,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/31225\/revisions\/31229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/media\/31228"}],"wp:attachment":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/media?parent=31225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/categories?post=31225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/tags?post=31225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}