{"id":24172,"date":"2021-03-05T16:22:41","date_gmt":"2021-03-05T16:22:41","guid":{"rendered":"https:\/\/todoapulmon-rafaela.com\/?p=24172"},"modified":"2021-03-05T16:22:41","modified_gmt":"2021-03-05T16:22:41","slug":"se-encuentran-abiertas-las-inscripciones-para-los-talleres-de-la-red-de-juventudes","status":"publish","type":"post","link":"https:\/\/todoapulmon-rafaela.com\/index.php\/2021\/03\/05\/se-encuentran-abiertas-las-inscripciones-para-los-talleres-de-la-red-de-juventudes\/","title":{"rendered":"Se encuentran abiertas las inscripciones para los talleres de la \u201cRed de Juventudes\u201d"},"content":{"rendered":"<p align=\"LEFT\">El programa municipal \u201cRed de Juventudes\u201d mantiene abiertas las inscripciones para los talleres que se desarrollar\u00e1n durante este a\u00f1o en la pileta del \u201cHogar &#8211; Granja El Ceibo\u00bb.<\/p>\n<p align=\"LEFT\">Los mismos est\u00e1n destinados a chicos y chicas de entre 10 y 22 a\u00f1os quienes podr\u00e1n optar entre ajedrez, hip hop, deportes, m\u00fasica, dibujo y pintura y folclore.<\/p>\n<p align=\"LEFT\">A trav\u00e9s de los talleres, se abordan diversas problem\u00e1ticas de adolescentes y j\u00f3venes mediante la generaci\u00f3n de espacios de contenci\u00f3n que brindan oportunidades para la construcci\u00f3n de proyectos de vida.<\/p>\n<p align=\"LEFT\">El subsecretario de Deportes y Recreaci\u00f3n, Ignacio Podio, dijo que \u201ceste programa tiene como objetivo brindar una continuidad en las pol\u00ecticas de inclusi\u00f3n para los j\u00f3venes que se iniciaron con las actividades de verano en la pileta y, ahora &#8211; desde marzo hasta diciembre \u2013 sigue con la puesta en marcha de 7 talleres que cuentan con la orientaci\u00f3n de un plantel de profesores y profesoras dispuestos a prestar acompa\u00f1amiento en cada uno de ellos\u201d.<\/p>\n<p align=\"LEFT\">El funcionario expres\u00f3 que \u201cen algunos casos las actividades se dividen en grupos para cumplir con los protocolos preventivos relacionados con la pandemia\u201d.<\/p>\n<p align=\"LEFT\"><b>Horarios e inscripciones<\/b><\/p>\n<p align=\"LEFT\">Los talleres de la \u201cRed de Juventudes\u201d ya est\u00e1n en marcha y las inscripciones se pueden concretar en el d\u00eda y horario de desarrollo de cada taller.<\/p>\n<p align=\"LEFT\">El detalle de las actividades, d\u00edas y horarios es el siguiente:<\/p>\n<p align=\"LEFT\">\u201cTaller de m\u00fasica\u201d; martes, de 17:30 a 19:00<\/p>\n<p align=\"LEFT\">\u201cTaller de ajedrez\u201d; mi\u00e9rcoles, de 17:30 a 19:00<\/p>\n<p align=\"LEFT\">\u201cTaller de deportes\u201d; martes y jueves, de 17:30 a 19:00<\/p>\n<p align=\"LEFT\">\u201cTaller de hip hop\u201d; viernes, de 15:00 a 17:00<\/p>\n<p align=\"LEFT\">\u201cTaller de dibujo\u201d; jueves, de 17:30 a 19:00<\/p>\n<p align=\"LEFT\">\u201cTaller de tela\u201d; viernes, de 15:00 a 17:00<\/p>\n<p align=\"LEFT\">\u201cTaller de folclore\u201d; mi\u00e9rcoles, de 18:00 a 20:00.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El programa municipal \u201cRed de Juventudes\u201d mantiene abiertas las inscripciones para los talleres que se desarrollar\u00e1n durante este a\u00f1o en<\/p>\n","protected":false},"author":2,"featured_media":24173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24],"tags":[],"class_list":["post-24172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias-destacadas"],"cc_featured_image_caption":{"caption_text":"Foto Prensa Municipalidad","source_text":"","source_url":""},"_links":{"self":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/24172"}],"collection":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/comments?post=24172"}],"version-history":[{"count":1,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/24172\/revisions"}],"predecessor-version":[{"id":24174,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/posts\/24172\/revisions\/24174"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/media\/24173"}],"wp:attachment":[{"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/media?parent=24172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/categories?post=24172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/todoapulmon-rafaela.com\/index.php\/wp-json\/wp\/v2\/tags?post=24172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}